{"id":30974,"date":"2022-03-28T11:01:47","date_gmt":"2022-03-28T11:01:47","guid":{"rendered":"http:\/\/www.sonova.com\/globale-datenschutzrichtlinie\/"},"modified":"2026-06-02T17:55:06","modified_gmt":"2026-06-02T17:55:06","slug":"globale-datenschutzrichtlinie","status":"publish","type":"page","link":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/","title":{"rendered":"Globale Datenschutzrichtlinie"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull pattern-hero has-sonova-header-background has-base-white-color has-brand-primary-dark-blue-background-color has-text-color has-background has-link-color wp-elements-1 has-global-padding is-content-justification-center is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--48-40);padding-bottom:var(--wp--preset--spacing--48-40)\">\n<div class=\"wp-block-group alignwide is-vertical is-content-justification-left is-layout-flex wp-container-core-group-is-layout-7c526d4b wp-block-group-is-layout-flex\" style=\"min-height:300px\"><h1 class=\"wp-block-post-title\">Globale Datenschutzrichtlinie<\/h1><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p><h2 class=\"wp-block-heading is-style-h1\">A. ALLGEMEINE INFORMATIONEN<\/h2><p class=\"wp-block-paragraph\">Die Sonova AG ist nach schweizerischem Recht gegr\u00fcndet; sie hat ihren Sitz in der Laubisr\u00fctistrasse 28, 8712 St\u00e4fa, Schweiz. Die Sonova AG, die als Datenverantwortliche fungiert, f\u00fchrt ihre Gesch\u00e4fte \u00fcber ihre weltweit verbundenen Unternehmen (zusammenfassend als \u201eSonova\u201c oder &#8220;Unternehmen&#8221; oder &#8220;wir&#8221; oder &#8220;unser&#8221; bezeichnet), die als unabh\u00e4ngige oder gemeinsame Datenverantwortliche in Bezug auf ihre Kunden, Nutzer von Produkten, mobilen Anwendungen und Websites sowie Auftragnehmer und Partner (&#8220;betroffene Personen&#8221;) handeln.<\/p><p class=\"wp-block-paragraph\">Das Unternehmen verarbeitet personenbezogene Daten im Rahmen seines Tagesgesch\u00e4fts. Aus diesem Grund wurde diese globale Datenschutzrichtlinie (<strong>&#8220;Richtlinie&#8221;<\/strong>) entworfen. Sie beschreibt die Praktiken des Unternehmens bei der Verwendung personenbezogener Daten. F\u00fcr einige Produkte und Dienstleistungen des Unternehmens sowie f\u00fcr bestimmte Dienstleistungen, die auf dieser Website angeboten werden, gelten weitere Datenschutzrichtlinien neben dieser Richtlinie.<\/p><p class=\"wp-block-paragraph\"><strong>&#8220;Personenbezogene Daten&#8221;<\/strong>sind alle Informationen, die sich auf identifizierbare nat\u00fcrliche Person beziehen.<\/p><p class=\"wp-block-paragraph\"><strong>&#8220;Sensible personenbezogene Daten&#8221;<\/strong>oder<strong>&#8220;besondere Kategorien personenbezogener Daten&#8221;<\/strong>sind grunds\u00e4tzlich alle Daten, die Pers\u00f6nlichkeitsrechte ber\u00fchren. Dazu z\u00e4hlen die Menschenw\u00fcrde, die pers\u00f6nliche Sicherheit und das Eigentum; ausserdem Daten, aus denen die ethnische Herkunft, politische Meinungen sowie religi\u00f6se oder philosophische \u00dcberzeugungen hervorgehen. Auch Informationen \u00fcber eine Gewerkschaftszugeh\u00f6rigkeit, Gesundheitsdaten, Daten \u00fcber das Sexualleben oder die sexuelle Orientierung sowie Finanzdaten sind eingeschlossen.<\/p><p class=\"wp-block-paragraph\">Die<strong>&#8220;Verarbeitung&#8221;<\/strong>bezeichnet jeden Vorgang im Zusammenhang mit personenbezogenen Daten. Dazu z\u00e4hlen etwa die Erhebung und Erfassung von Daten sowie die Speicherung, Verwendung, Offenlegung und \u00dcbermittlung; ausserdem der Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder das Vernichten von Daten.<\/p><p class=\"wp-block-paragraph\"><strong>&#8220;Betroffene Personen&#8221;<\/strong>bezeichnet jede identifizierbare nat\u00fcrliche Person, \u00fcber die Informationen erhoben und\/oder verarbeitet werden. In dieser Richtlinie umfasst der Begriff &#8220;betroffene Personen&#8221; Kunden, Nutzer von Produkten, mobilen Anwendungen und Websites, sowie Auftragnehmer und Partner.<strong>&#8220;Datenverantwortlicher&#8221;<\/strong>ist jede nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung personenbezogener Daten entscheidet. In \u00dcbereinstimmung mit den geltenden Gesetzen kann auf den Begriff &#8220;Datenverantwortlicher&#8221; mit anderen Begriffen verwiesen werden, wenn die grundlegende Rolle unver\u00e4ndert bleibt. Zum Beispiel kann diese Rolle in \u00dcbereinstimmung mit der Anwendung des Gesetzes zum Schutz personenbezogener Daten (PIPL) in China alternativ als &#8220;Auftragsverarbeiter f\u00fcr personenbezogene Daten&#8221; bezeichnet werden.<\/p><h2 class=\"wp-block-heading is-style-h1\">B. ANWENDBARES RECHT<\/h2><p class=\"wp-block-paragraph\">Das Unternehmen verpflichtet sich, die jeweils geltenden Datenschutzgesetze (<strong>&#8220;anwendbare Gesetze&#8221;)\u00a0<\/strong>zu befolgen. Bestimmte Anforderungen k\u00f6nnen jedoch von Land zu Land unterschiedlich sein. So verpflichtet sich das Unternehmen, die folgenden Gesetze einzuhalten:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">die Verordnung (EU) 2016\/679 des Europ\u00e4ischen Parlaments und des Rates vom 27. April 2016 zum Schutz nat\u00fcrlicher Personen bei der Verarbeitung personenbezogener Daten, zum freien<\/li><\/ul><p class=\"wp-block-paragraph\">Datenverkehr und zur Aufhebung der Richtlinie 95\/46\/EG (Datenschutz-Grundverordnung) (&#8220;DSGVO&#8221;)<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">das Schweizerische Bundesgesetz \u00fcber den Datenschutz vom 19. Juni 1992 (&#8220;DSG&#8221;), ge\u00e4ndert im Jahr 2020 und in Kraft ab September 2023<\/li><li class=\"wp-block-list-item\">den California Consumer Privacy Act von 2018 (&#8220;CCPA&#8221;) in der durch den California Privacy Rights Act von 2020 (&#8220;CPRA&#8221;) ge\u00e4nderten Fassung<\/li><li class=\"wp-block-list-item\">den Health Insurance Portability and Accountability Act von 1996 (&#8220;HIPAA&#8221;), Public Law 104\u2013191,<\/li><\/ul><p class=\"wp-block-paragraph\">Abschnitte 261\u2013264, ge\u00e4ndert durch den Health Information Technology for Economic and Clinical Health Act, aufgenommen in den American Recovery and Reinvestment Act von 2009 (&#8220;HITECH&#8221;) und alle anwendbaren Durchf\u00fchrungsvorschriften, einschliesslich, aber nicht beschr\u00e4nkt auf die Standards f\u00fcr den Schutz individuell identifizierbarer Gesundheitsinformationen, die Security Rule und Breach Notification Rule, kodifiziert in 45 C.F.R. Teile 160 und 164 (alle diese Gesetze und Vorschriften werden zusammenfassend als &#8220;HIPAA&#8221; bezeichnet)<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">das Gesetz zum Schutz personenbezogener Daten (&#8220;PIPL&#8221;), das Cybersicherheitsgesetz (&#8220;CSL&#8221;), das B\u00fcrgerliche Gesetzbuch, das Datensicherheitsgesetz (&#8220;DSL&#8221;) sowie andere geltende Gesetze und Vorschriften, beh\u00f6rdliche Anforderungen sowie nationale Standards (zusammen die chinesischen Datenschutzgesetze).<\/li><\/ul><h2 class=\"wp-block-heading is-style-h1\">C. ERHOBENE PERSONENBEZOGENE DATEN<\/h2><p class=\"wp-block-paragraph\">Das Unternehmen kann die folgenden personenbezogenen Daten verarbeiten:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Identit\u00e4tsdaten: Name, Vorname, Alias, Staatsangeh\u00f6rigkeit und Geburtsdatum<\/li><li class=\"wp-block-list-item\">Kontaktdaten: Postanschrift, private Telefonnummer, private E-Mail-Adresse oder Notfallkontakt,<\/li><li class=\"wp-block-list-item\">Sozialversicherungsnummer und Versicherungsgesellschaft<\/li><li class=\"wp-block-list-item\">Finanzdaten: Zahlungsmittel (inkl. Kredit- oder Debitkartennummer), Finanzinstituts- und Bankdaten, IBAN, Krankenkassen- oder Versicherungsinformationen<\/li><li class=\"wp-block-list-item\">Gesundheitsdaten, einschliesslich Gewicht, Gr\u00f6sse, Krankengeschichte, \u00e4rztliche Verschreibung, H\u00f6rf\u00e4higkeit, Verfolgung k\u00f6rperlicher Aktivit\u00e4t (Schrittzahl, Trainingsintensit\u00e4t, Trainingsminuten), Fitnessdaten (Herzfrequenz, Energieverbrauch, Blutdruck)<\/li><li class=\"wp-block-list-item\">Daten \u00fcber das Nutzerverhalten auf der Website: Navigationsdaten, IP-Adresse (Internet Protocol), Cookies und andere Tracking-Tools<\/li><li class=\"wp-block-list-item\">Daten zu den gekauften Produkten: Modell, Seriennummer, Nutzungsdaten<\/li><li class=\"wp-block-list-item\">Daten in Bezug auf Konten einschliesslich Zugangsdaten f\u00fcr Konten (z. B. Benutzernamen, Kontonummern)<\/li><li class=\"wp-block-list-item\">Daten im Zusammenhang mit den erbrachten Dienstleistungen<\/li><li class=\"wp-block-list-item\">Daten in Bezug auf das Feedback zu unseren Produkten und Dienstleistungen, einschliesslich Kommentaren und Notizen.<\/li><\/ul><h2 class=\"wp-block-heading is-style-h1\">D. ZWECKE DER VERARBEITUNG PERSONENBEZOGENER DATEN<\/h2><p class=\"wp-block-paragraph\">Das Unternehmen st\u00fctzt sich bei der Verarbeitung personenbezogener Daten auf die folgenden Rechtsgrundlagen:<\/p><h2 class=\"wp-block-heading\">D.1 VERARBEITUNG AUF DER GRUNDLAGE DER EINWILLIGUNG DER BETROFFENEN PERSONEN<\/h2><p class=\"wp-block-paragraph\">Die Verarbeitung personenbezogener Daten kann auf der Einwilligung der betroffenen Personen beruhen. Die Verarbeitung kann dabei Folgendes umfassen:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Marketingzwecke wie das Versenden von Newslettern und Informationen \u00fcber Produkte und<\/li><\/ul><p class=\"wp-block-paragraph\">Dienstleistungen, die vom Unternehmen angeboten werden,<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Erstellung des Kontos der betroffenen Personen,<\/li><li class=\"wp-block-list-item\">Online-H\u00f6rtests,<\/li><li class=\"wp-block-list-item\">Profiling, um Aktualisierungen der Produkte und Dienstleistungen anzubieten, die vom Unternehmen f\u00fcr die betroffenen Personen entwickelt und zugeschnitten wurden,<\/li><li class=\"wp-block-list-item\">Einladung der betroffenen Personen zu klinischen Studien sowie Forschungs- oder Testimonial-<\/li><\/ul><p class=\"wp-block-paragraph\">Initiativen,<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Einschreibung in unsere Communities \u00fcber Online-Formulare,<\/li><li class=\"wp-block-list-item\">Teilnahme an Wettbewerben und Verlosungen,<\/li><li class=\"wp-block-list-item\">Teilnahme an Online-Umfragen,<\/li><li class=\"wp-block-list-item\">Teilnahme an Veranstaltungen, Schulungen oder Webinaren.<\/li><li class=\"wp-block-list-item\">Ver\u00f6ffentlichung von Kommentaren auf unserer Plattform: Bitte beachten Sie, dass Kommentare und Meinungs\u00e4usserungen zu unseren Blogs mit Ihrem Namen ver\u00f6ffentlicht werden. Bitte ber\u00fccksichtigen Sie auch, dass wir in diesen F\u00e4llen nicht f\u00fcr Ihre personenbezogenen Daten verantwortlich sind und auch nicht daf\u00fcr, Ihre \u00f6ffentlichen Kommentare zu entfernen oder zu bearbeiten.<\/li><\/ul><p class=\"wp-block-paragraph\">F\u00fcr die Verarbeitung der oben genannten personenbezogenen Daten werden wir alle vorgeschriebenen rechtlichen Erfordernisse beachten.<\/p><h2 class=\"wp-block-heading\">D.2 VERARBEITUNG AUF DER GRUNDLAGE EINES VERTRAGS<\/h2><p class=\"wp-block-paragraph\">Die Verarbeitung personenbezogener Daten kann auf einem Vertrag oder auf vorvertraglichen Vereinbarungen beruhen und Folgendes umfassen:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Erf\u00fcllung unserer vertraglichen oder vorvertraglichen Pflichten gegen\u00fcber der betroffenen Person, einschliesslich des technischen Betriebs und der Funktionalit\u00e4t der von ihnen erworbenen Produkte und Dienstleistungen,<\/li><li class=\"wp-block-list-item\">Bereitstellung von After-Sales-Services nach dem Kauf von Produkten und Dienstleistungen,<\/li><li class=\"wp-block-list-item\">Sozialversicherungs- oder Versicherungsabwicklung, einschliesslich der Abrechnung der erworbenen Produkte oder Dienstleistungen,<\/li><li class=\"wp-block-list-item\">Verwaltung und Abwicklung von Reklamationen,<\/li><li class=\"wp-block-list-item\">Beratung und Interaktion, wenn die betroffene Person das Unternehmen kontaktiert, zum Beispiel \u00fcber Formulare, die Kommentarfunktion, die Chat-Funktion oder E-Mails,<\/li><li class=\"wp-block-list-item\">Kontaktaufnahme mit der betroffenen Person, um auf (technische) Anfragen und Beschwerden zu antworten,<\/li><li class=\"wp-block-list-item\">Kontaktaufnahme mit der betroffenen Person oder mit ihren Vertretern, um die angeforderte kommerzielle Unterst\u00fctzung anzubieten \u2013 etwa f\u00fcr einen Termin mit dem H\u00f6rger\u00e4teakustiker oder anbieter.<\/li><\/ul><h2 class=\"wp-block-heading\">D.3 VERARBEITUNG AUF DER GRUNDLAGE EINES BERECHTIGTEN INTERESSES<\/h2><p class=\"wp-block-paragraph\">Die Verarbeitung personenbezogener Daten kann auf dem berechtigten Interesse des Unternehmens beruhen, unsere Produkte und Dienstleistungen zu verbessern. Die Verarbeitung personenbezogener Daten zu diesem Zweck kann auf der Grundlage der geltenden Gesetze Folgendes umfassen:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Durchf\u00fchrung von statistischen Nutzungsanalysen,<\/li><li class=\"wp-block-list-item\">Durchf\u00fchrung interner administrativer Funktionen,<\/li><li class=\"wp-block-list-item\">Schutz vor betr\u00fcgerischen Aktivit\u00e4ten und Verbesserung der Sicherheit. So verarbeiten wir Ihre EMail-Adresse, um einen zuf\u00e4llig generierten Code zu \u00fcbermitteln, der den Abschluss Ihres Anmeldevorgangs markiert.<\/li><li class=\"wp-block-list-item\">Verwaltung von Beziehungen zu betroffenen Personen,<\/li><li class=\"wp-block-list-item\">Bewertung unserer Produkte und Dienstleistungen,<\/li><li class=\"wp-block-list-item\">Analyse der Website-Performance, um unsere Dienstleistungen und unsere Website zu verbessern,<\/li><li class=\"wp-block-list-item\">Vermarktung von Produkten oder Dienstleistungen, die das Unternehmen Gesch\u00e4ftspartnern oder Auftragnehmern anbietet. Bitte beachten Sie, dass Sonova bei Bedarf die Einwilligung der betroffenen Personen einholt, bevor sie personenbezogene Daten zu Marketingzwecken verarbeitet.<\/li><\/ul><h2 class=\"wp-block-heading\">D.4 VERARBEITUNG AUF DER GRUNDLAGE ANDERER GRUNDLAGEN<\/h2><p class=\"wp-block-paragraph\">Das Unternehmen kann personenbezogene Daten auch verarbeiten, um geltende Gesetze und weitere vorgeschriebene Normen einzuhalten. Diese Verarbeitung erfolgt auf der Grundlage von Artikel 6 Absatz 1 Buchstabe c) der DSGVO, welcher die Verarbeitung personenbezogener Daten zur Erf\u00fcllung einer rechtlichen Verpflichtung erlaubt, der der Verantwortliche unterliegt.<\/p><p class=\"wp-block-paragraph\">Je nach Wohnsitz der betroffenen Personen kann sich unsere Verarbeitung bestimmter personenbezogener Daten an anderen Rechtsgrundlagen orientieren.<\/p><h2 class=\"wp-block-heading is-style-h1\">E. COOKIES UND ANDERE TRACKING-TOOLS<\/h2><p class=\"wp-block-paragraph\">Cookies und andere Tracking-Tools sind kleine Dateien, die von den meisten Internet-Browsern gespeichert werden, um Besucherinformationen zu verfolgen. Sie erm\u00f6glichen es Sonova, ihr Webangebot f\u00fcr Sie interessanter zu gestalten. W\u00e4hrend Ihres Besuchs auf unserer Website kann Sonova je nach Website vier Kategorien von Cookies und anderen Tracking-Tools verwenden. Die Aufbewahrungsfrist h\u00e4ngt vom jeweiligen Land und dem jeweils anwendbaren Recht ab. Beachten Sie die erg\u00e4nzenden Datenschutzhinweise, die Sie \u00fcber die Cookies der von Ihnen besuchten Websites informieren.<\/p><p class=\"wp-block-paragraph\">Wir verwenden Cookies und andere Tracking-Tools f\u00fcr:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Informationen \u00fcber Ihre Browser-Einstellungen, den Domain-Namen, den Internetdienstanbieter, Ihr Betriebssystem, das Datum und die Uhrzeit des Zugriffs, den Standort und die Art Ihres Ger\u00e4ts<\/li><li class=\"wp-block-list-item\">Informationen \u00fcber andere Websites, die Sie besucht haben, oder \u00fcber Ihre Suchanfragen<\/li><li class=\"wp-block-list-item\">den Schutz vor betr\u00fcgerischen Aktivit\u00e4ten und f\u00fcr eine verbesserte Sicherheit<\/li><li class=\"wp-block-list-item\">Kenntnisse \u00fcber Ihre Browsing-Pr\u00e4ferenzen und \u00fcber Produkte, an denen Sie interessiert sind.<\/li><\/ul><p class=\"wp-block-paragraph\">Einige der Cookies und anderen Tracking-Tools auf unseren Websites werden von uns gesetzt, andere von Dritten in unserem Auftrag. All das erm\u00f6glicht massgeschneiderte Werbung f\u00fcr Sonova auch auf anderen Websites, die Sie besuchen.<\/p><p class=\"wp-block-paragraph\">Abh\u00e4ngig von der jeweiligen Website k\u00f6nnen wir die folgenden Kategorien von Cookies und anderen Tracking-Tools verwenden:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Unbedingt erforderliche Cookies sind notwendig, damit wir Ihnen die grundlegenden Funktionen unserer Website zur Verf\u00fcgung stellen k\u00f6nnen.<\/li><li class=\"wp-block-list-item\">Leistungs- und Analyse-Cookies erm\u00f6glichen es uns, Aktivit\u00e4ten zu erfassen, um die Website zu verbessern.<\/li><li class=\"wp-block-list-item\">Funktionale Cookies werden verwendet, um den pers\u00f6nlichen Website-Besuch zu optimieren.<\/li><li class=\"wp-block-list-item\">Targeting- oder Werbe-Cookies k\u00f6nnen von unseren Werbepartnern \u00fcber unsere Website gesetzt werden, um ein Profil Ihrer Interessen zu erstellen und relevante Werbung vorzuschlagen.<\/li><\/ul><p class=\"wp-block-paragraph\">Jede Art von Cookie spiegelt einen bestimmten Zweck wider. Auf unserer Website k\u00f6nnen Sie jedem Zweck zustimmen. Wenn Sie alle Cookies akzeptieren, haben Sie ein vollst\u00e4ndig personalisiertes WebErlebnis. Sie k\u00f6nnen w\u00e4hlen, welche Arten von Cookies Sie akzeptieren oder blockieren m\u00f6chten. Sie k\u00f6nnen aber auch von uns angebotene Dienste nutzen, wenn Sie einigen Cookies nicht zustimmen \u2013 es sei denn, die Ablehnung bezieht sich auf unbedingt erforderliche Cookies. Ihre Einwilligung k\u00f6nnen Sie jederzeit widerrufen oder \u00e4ndern, indem Sie auf die Seite &#8220;Cookie-Einstellungen&#8221; gehen.<\/p><p class=\"wp-block-paragraph\">Die Art und Weise, wie Sie Ihre Zustimmung erteilen oder alle Cookies akzeptieren, h\u00e4ngt von den geltenden Gesetzen in Ihrem Land ab und ist im Cookie-Banner leicht zu finden.<\/p><p class=\"wp-block-paragraph\">Wenn Sie nicht an den Vorteilen unserer Cookies interessiert sind, k\u00f6nnen Sie \u00fcber die &#8220;Hilfe&#8221;-Funktion Ihres Browsers Anweisungen erhalten, wie Sie Cookies verhindern oder vorhandene Cookies l\u00f6schen k\u00f6nnen. Ausserdem erfahren Sie, wie Sie alle neuen Cookies in Ihrem Browser blockieren k\u00f6nnen und welche Schritte erforderlich sind, um eine Benachrichtigung \u00fcber neue Cookies zu erhalten.<\/p><p class=\"wp-block-paragraph\">Hilfreiche Informationen zu Cookies finden Sie auf diesen Websites: http:\/\/www.allaboutcookies.org\/ oder https:\/\/cookiepedia.co.uk.<\/p><p class=\"wp-block-paragraph\">Weitere Einzelheiten zu den Kategorien von Cookies und anderen Tracking-Tools werden \u00fcber das Cookie-Banner und den entsprechenden Cookie-Bereich bereitgestellt.<\/p><h2 class=\"wp-block-heading is-style-h1\">F. SOCIAL-MEDIA-PLUGINS<\/h2><p class=\"wp-block-paragraph\">Social-Media-Plugins sind Bestandteil bestimmter Webseiten von Sonova; sie dienen Social-MediaAnbietern wie Facebook, Instagram, Twitter, LinkedIn, Google+ und YouTube. Wenn Sie auf ein solches Plugin klicken, stellt Ihr Browser eine Verbindung mit dem jeweiligen Social-Media-Server her. Gleichzeitig erf\u00e4hrt der Anbieter, dass Sie unsere Website besucht haben, bevor Sie auf der Social-Media-Seite gelandet sind. Wenn Sie bei dem jeweiligen Anbieter registriert sind und sich eingeloggt haben, kann Ihr Besuch auch mit Ihrem Benutzerkonto verkn\u00fcpft werden. Anbieter machen in der Regel keine Angaben dazu, welche Daten bei der Nutzung ihrer Social-Media-Plugins \u00fcbermittelt werden. Uns ist es daher nicht abschliessend m\u00f6glich, den Inhalt und Umfang der \u00fcbermittelten Daten sowie deren Nutzung durch diese Anbieter zu \u00fcberpr\u00fcfen. Weitere Informationen zu Social-Media-Plugins entnehmen Sie bitte den Datenschutzbestimmungen des jeweiligen Anbieters. Wenn Sie nicht m\u00f6chten, dass ein Anbieter \u00fcber unsere Website Daten \u00fcber Sie sammelt, deaktivieren Sie bitte die Plugins in Ihrem Webbrowser. Wenn Sie eine Verkn\u00fcpfung mit einem bestehenden Benutzerkonto vermeiden m\u00f6chten, m\u00fcssen Sie sich vor dem Besuch unserer Website auf der Social-Media-Website ausloggen.<\/p><h2 class=\"wp-block-heading is-style-h1\">G. LINKS ZU DRITTANBIETERN<\/h2><p class=\"wp-block-paragraph\">Diese Richtlinie gilt ausschliesslich f\u00fcr die Nutzung dieser Website. Wir k\u00f6nnen Ihnen Links zu Websites von Dritten zur Verf\u00fcgung stellen, die f\u00fcr Sie von Interesse sein k\u00f6nnten. Bitte beachten Sie jedoch, dass Sonova nicht f\u00fcr den Inhalt solcher Websites verantwortlich ist und deren Datenschutzsicherheit nicht garantieren kann. Wir empfehlen Ihnen, die Datenschutzerkl\u00e4rungen auf den jeweiligen Websites zu lesen, um zu verstehen, wie Ihre personenbezogenen Daten von diesen Drittanbietern verarbeitet werden.<\/p><h2 class=\"wp-block-heading is-style-h1\">H. AUFBEWAHRUNG PERSONENBEZOGENER DATEN<\/h2><p class=\"wp-block-paragraph\">Personenbezogene Daten werden nicht l\u00e4nger aufbewahrt, als es f\u00fcr die oben genannten Zwecke erforderlich ist. Das bedeutet, dass personenbezogene Daten gel\u00f6scht werden, sobald der Zweck der Datenverarbeitung erreicht ist. Das Unternehmen kann personenbezogene Daten jedoch l\u00e4nger aufbewahren, wenn dies nach geltendem Recht erforderlich ist; dies, um Rechte zu sch\u00fctzen oder auszu\u00fcben.<\/p><p class=\"wp-block-paragraph\">Am Ende der Aufbewahrungsfrist muss das Unternehmen m\u00f6glicherweise auch personenbezogene Daten archivieren, um die geltenden Gesetze einzuhalten, und zwar f\u00fcr einen begrenzten Zeitraum und mit eingeschr\u00e4nktem Zugriff.<\/p><p class=\"wp-block-paragraph\">Diese Aufbewahrungsfristen k\u00f6nnen je nach Land, in dem die betroffenen Personen ans\u00e4ssig sind, und in \u00dcbereinstimmung mit den geltenden Gesetzen variieren.<\/p><h2 class=\"wp-block-heading is-style-h1\">I. WEITERGABE PERSONENBEZOGENER DATEN<\/h2><p class=\"wp-block-paragraph\">Das Unternehmen kann personenbezogene Daten \u2013 die Einwilligung und\/oder eine Rechtsgrundlage vorausgesetzt \u2013 an folgende Dritte weitergeben:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Gesch\u00e4ftspartner, die in unserem Auftrag Dienstleistungen erbringen, etwa f\u00fcr technischen Support, Marketingzwecke oder andere Arten von Dienstleistungen<\/li><li class=\"wp-block-list-item\">Beh\u00f6rden und andere staatliche Einrichtungen f\u00fcr Dienstleistungen, um die Rechte der betroffenen Personen oder unsere Rechte zu sch\u00fctzen; ferner, um das Eigentum oder die Sicherheit anderer zu sch\u00fctzen und um die Sicherheit unserer Dienste aufrechtzuerhalten. Eine Weitergabe personenbezogener Daten behalten wir uns auch vor, wenn wir aufgrund geltender Gesetze sowie gerichtlicher oder beh\u00f6rdlicher Vorschriften dazu verpflichtet sind oder wenn eine Offenlegung f\u00fcr rechtliche Ermittlungen erforderlich ist<\/li><li class=\"wp-block-list-item\">Vertreter, die nach geltendem Recht autorisiert sind, die Betreuung der betroffenen Person wahrzunehmen, einschliesslich der Familie und enger Freunde.<\/li><\/ul><p class=\"wp-block-paragraph\">Abh\u00e4ngig von den geltenden Gesetzen schliessen wir Vertr\u00e4ge mit Dritten ab, um sicherzustellen, dass personenbezogene Daten auf der Grundlage unserer Anweisungen sowie in \u00dcbereinstimmung mit dieser Richtlinie und anderen Vertraulichkeits- und Sicherheitsmassnahmen verarbeitet werden.<\/p><p class=\"wp-block-paragraph\">Von Zeit zu Zeit kann es notwendig sein, solche Vertr\u00e4ge innerhalb der Sonova Gruppe, mit Tochtergesellschaften und verbundenen Unternehmen abzuschliessen, um regulatorische Anforderungen zu erf\u00fcllen. Dabei gelten auch Tochtergesellschaften und verbundene Unternehmen von Sonova als Dritte.<\/p><h2 class=\"wp-block-heading is-style-h1\">J. \u00dcBERMITTLUNG PERSONENBEZOGENER DATEN<\/h2><p class=\"wp-block-paragraph\">Die oben genannten Dritten wie verbundene Unternehmen und Tochtergesellschaften von Sonova sowie Gesch\u00e4ftspartner und Beh\u00f6rden, an die wir personenbezogene Daten weitergeben k\u00f6nnen, befinden sich m\u00f6glicherweise auch in L\u00e4ndern, deren Datenschutzgesetze von den unseren abweichen.<\/p><p class=\"wp-block-paragraph\">Wenn personenbezogene Daten innerhalb der Europ\u00e4ischen Union oder im Europ\u00e4ischen Wirtschaftsraum verarbeitet werden und personenbezogene Daten an Dritte in einem Land weitergegeben werden, das nach Ansicht der Europ\u00e4ischen Kommission keinen angemessenen Schutz bietet, stellt das Unternehmen Folgendes sicher:<\/p><ul class=\"wp-block-list\"><li class=\"wp-block-list-item\">Implementierung von angemessenen Verfahren zur Einhaltung der geltenden Gesetze, insbesondere wenn ein Antrag auf Genehmigung durch die zust\u00e4ndige Aufsichtsbeh\u00f6rde erforderlich ist<\/li><li class=\"wp-block-list-item\">Implementierung von geeigneten organisatorischen, technischen und rechtlichen Sicherheitsvorkehrungen, um die besagte \u00dcbertragung zu regeln und das erforderliche und angemessene Schutzniveau nach geltendem Recht zu gew\u00e4hrleisten<\/li><li class=\"wp-block-list-item\">falls erforderlich die Umsetzung von Standardvertragsklauseln, wie sie von der Europ\u00e4ischen Kommission verabschiedet wurden<\/li><li class=\"wp-block-list-item\">falls erforderlich und abh\u00e4ngig vom Land des Dritten, der die Daten importiert, die Implementierung zus\u00e4tzlicher Massnahmen, wie zum Beispiel einer Angemessenheitspr\u00fcfung der Daten\u00fcbertragung und gegebenenfalls erg\u00e4nzender Massnahmen zum Schutz der \u00fcbermittelten personenbezogenen Daten.<\/li><\/ul><p class=\"wp-block-paragraph\">Wenn personenbezogene Daten nicht innerhalb der Europ\u00e4ischen Union oder im Europ\u00e4ischen Wirtschaftsraum verarbeitet werden oder an Dritte ausserhalb Ihres Landes weitergegeben werden, stellt das Unternehmen angemessene Sicherheitsvorkehrungen zum Schutz personenbezogener Daten sicher. Daf\u00fcr werden geeignete rechtliche Mechanismen umgesetzt. Diese Mechanismen k\u00f6nnen je nach Land und Gesetzen unterschiedlich sein.<\/p><p class=\"wp-block-paragraph\">Wenn die personenbezogenen Daten einer betroffenen Person unter die Anwendung des revidierten DSG oder PIPL fallen und internationalen \u00dcbermittlungen unterliegen, wird die betroffene Person \u00fcber diese \u00dcbermittlungen informiert. Solche Mitteilungen enthalten Details und Sicherheitsvorkehrungen in Bezug auf die \u00dcbermittlung personenbezogener Daten ausserhalb der Schweiz bzw. Chinas.<\/p><h2 class=\"wp-block-heading is-style-h1\">K. SICHERHEIT PERSONENBEZOGENER DATEN<\/h2><p class=\"wp-block-paragraph\">Die Sicherheit personenbezogener Daten ist uns \u00e4usserst wichtig. Wir ergreifen alle angemessenen Schritte, um zu gew\u00e4hrleisten, dass diese Daten sicher und in \u00dcbereinstimmung mit dieser Richtlinie behandelt werden.<\/p><p class=\"wp-block-paragraph\">Sonova setzt eine Vielzahl von Sicherheitsmassnahmen ein, um personenbezogene Daten umfassend zu sch\u00fctzen. Diese Massnahmen basieren auf angemessenen Sicherheitsstandards der Branche und umfassen unter anderem Zugriffskontrollen, Passw\u00f6rter, Verschl\u00fcsselungen und regelm\u00e4ssige Sicherheitsbewertungen.<\/p><p class=\"wp-block-paragraph\">Alle Mitarbeitenden, die personenbezogene Daten verarbeiten k\u00f6nnen, sind zu einer angemessenen Schulung verpflichtet, um die Einhaltung der Datenschutzbestimmungen zu gew\u00e4hrleisten.<\/p><p class=\"wp-block-paragraph\">Wir \u00fcberpr\u00fcfen regelm\u00e4ssig unsere Informationssicherheitsverfahren, um geeignete neue Technologien und Methoden in Betracht zu ziehen.<\/p><h2 class=\"wp-block-heading is-style-h1\">L. DATENSCHUTZRECHTE IN BEZUG AUF PERSONENBEZOGENE DATEN<\/h2><p class=\"wp-block-paragraph\">Abh\u00e4ngig von den einschl\u00e4gigen Gesetzen haben die betroffenen Personen Rechte in Bezug auf ihre personenbezogenen Daten. Sie k\u00f6nnen den Zugang, die Berichtigung und die L\u00f6schung ihrer personenbezogenen Daten verlangen. Ausserdem k\u00f6nnen sie Widerspruch gegen die Verarbeitung und Daten\u00fcbertragbarkeit einlegen sowie ihre Einwilligung zur Verarbeitung personenbezogener Daten widerrufen. Betroffene Personen k\u00f6nnen auch der automatisierten Entscheidungsfindung im Einzelfall widersprechen, wenn sie Bedenken gegen eine solche Verarbeitung haben.<\/p><p class=\"wp-block-paragraph\">F\u00fcr die Rechte der betroffenen Personen gelten die gesetzlichen Fristen.<\/p><p class=\"wp-block-paragraph\">Dar\u00fcber hinaus k\u00f6nnen einige Gesetze Anweisungen in Bezug auf die Aufbewahrung, \u00dcbermittlung und L\u00f6schung personenbezogener Daten posthum enthalten.<\/p><p class=\"wp-block-paragraph\">Um diese Datenschutzrechte auszu\u00fcben, k\u00f6nnen sich betroffene Personen an uns wenden \u2013 wie im Abschnitt &#8220;Wie Sie uns kontaktieren k\u00f6nnen&#8221; unten beschrieben. Wir k\u00f6nnen einen Identit\u00e4tsnachweis verlangen, um auf die Anfrage zu antworten. Wenn wir dem Antrag nicht nachkommen k\u00f6nnen (Ablehnung oder Einschr\u00e4nkung), werden wir unsere Entscheidung schriftlich dokumentieren.<\/p><p class=\"wp-block-paragraph\">Die Aus\u00fcbung dieser Rechte ist nicht absolut und unterliegt den Einschr\u00e4nkungen der geltenden Gesetze. Keine Person darf aufgrund der Aus\u00fcbung dieser Rechte Vergeltungsmassnahmen oder Diskriminierung ausgesetzt sein.<\/p><p class=\"wp-block-paragraph\">Betroffene Personen haben m\u00f6glicherweise das Recht, eine Beschwerde bei der \u00f6rtlichen Aufsichtsbeh\u00f6rde oder der zust\u00e4ndigen Aufsichtsbeh\u00f6rde einzureichen, wenn sie der Ansicht sind, dass die Verarbeitung ihrer personenbezogenen Daten gegen geltende Gesetze verst\u00f6sst.<\/p><h2 class=\"wp-block-heading is-style-h1\">M. AKTUALISIERUNGEN DIESER RICHTLINIE<\/h2><p class=\"wp-block-paragraph\">Wir k\u00f6nnen diese Richtlinie von Zeit zu Zeit aktualisieren, um neue oder andere Datenschutzpraktiken widerzuspiegeln. In diesem Fall werden wir aktualisierte Versionen dieser Richtlinie auf dieser Seite ver\u00f6ffentlichen. Eine \u00fcberarbeitete Richtlinie gilt nur f\u00fcr Daten, die nach dem Datum ihres Inkrafttretens erhoben werden. Wir empfehlen den betroffenen Personen, diese Seite regelm\u00e4ssig zu besuchen, um die neuesten Informationen zu unseren Datenschutzpraktiken zu erhalten.<\/p><h2 class=\"wp-block-heading is-style-h1\">N. WIE SIE UNS KONTAKTIEREN K\u00d6NNEN<\/h2><p class=\"wp-block-paragraph\">Bei Fragen, Kommentaren oder Bedenken zu dieser Richtlinie oder zur Aus\u00fcbung der Datenschutzrechte, die nach geltendem Recht in Bezug auf personenbezogene Daten zul\u00e4ssig sind, wenden Sie sich bitte an unseren Datenschutzbeauftragten unter:<\/p><p class=\"wp-block-paragraph\">Sonova AG<\/p><p class=\"wp-block-paragraph\">z. Hd. Datenschutzbeauftragter<\/p><p class=\"wp-block-paragraph\">Laubisr\u00fctistrasse 28<\/p><p class=\"wp-block-paragraph\">8712 St\u00e4fa, Schweiz +41 58 928 01 01<u>privacy@sonova.com<\/u>\u00a0<\/p><p class=\"wp-block-paragraph\"><strong>Informationsblatt zu den Sonova-Politik<\/strong><\/p><figure><figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Name der Politik<\/strong><\/td><td>Globale Datenschutzrichtlinie<\/td><\/tr><tr><td><strong>Datum des Inkrafttretens<\/strong><\/td><td>01 April 2025<\/td><\/tr><tr><td><strong>Ebene in der Politikhierarchie<\/strong><\/td><td>Schl\u00fcsselpolitik (Level 2)<\/td><\/tr><tr><td><strong>Geltungsbereich und Zielgruppe<\/strong><\/td><td>Alle Mitarbeitenden von Sonova, weltweit<\/td><\/tr><tr><td><strong>MB-Bezeichnung<\/strong><\/td><td>Vorsitzender der Gesch\u00e4ftsf\u00fchrung<\/td><\/tr><tr><td><strong>Politikbesitzer<\/strong><\/td><td>Konzern-Compliance-Beauftragter<\/td><\/tr><\/tbody><\/table><\/figure><\/figure><p class=\"wp-block-paragraph\"><strong>Versionskontrolle<\/strong><\/p><figure><figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Version<\/strong><\/td><td><strong>Beschreibung der \u00c4nderung \/ Inhalt<\/strong><\/td><td><strong>Herausgegeben<\/strong><\/td><\/tr><tr><td><strong>2.00<\/strong><\/td><td>Die Web- und Cookie-Richtlinie wurde in dieses Dokument aufgenommen und aktualisiert, um das geltende Recht widerzuspiegeln.<\/td><td><strong>01.04.2025<\/strong><\/td><\/tr><tr><td><strong>1.00<\/strong><\/td><td>Erste Ver\u00f6ffentlichung der Richtlinie<\/td><td><strong>01.02.2022<\/strong><\/td><\/tr><\/tbody><\/table><\/figure><\/figure><p class=\"wp-block-paragraph\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Globale Datenschutzrichtlinie \u00a0A. ALLGEMEINE INFORMATIONENDie Sonova AG ist nach schweizerischem Recht gegr\u00fcndet; sie hat ihren Sitz in der Laubisr\u00fctistrasse 28, 8712 St\u00e4fa, Schweiz. Die Sonova AG, die als Datenverantwortliche fungiert, f\u00fchrt ihre Gesch\u00e4fte \u00fcber ihre weltweit verbundenen Unternehmen (zusammenfassend als \u201eSonova\u201c oder &#8220;Unternehmen&#8221; oder &#8220;wir&#8221; oder &#8220;unser&#8221; bezeichnet), die als unabh\u00e4ngige oder gemeinsame Datenverantwortliche in [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_sonova_workflow_status_change":false,"_sonova_post_revision":0,"_sonova_post_revision_main_post_id":0,"_assigned_reviewer":[],"_assigned_translator":[],"_reviewer_notes":[],"_sonova_hreflang_group":"","sonova_disable_hero_pattern":false,"footnotes":""},"news-type":[62],"class_list":["post-30974","page","type-page","status-publish","hentry","news-type-page"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Datenschutzrichtlinie - Sonova International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Datenschutzrichtlinie - Sonova International\" \/>\n<meta property=\"og:description\" content=\"Globale Datenschutzrichtlinie \u00a0A. ALLGEMEINE INFORMATIONENDie Sonova AG ist nach schweizerischem Recht gegr\u00fcndet; sie hat ihren Sitz in der Laubisr\u00fctistrasse 28, 8712 St\u00e4fa, Schweiz. Die Sonova AG, die als Datenverantwortliche fungiert, f\u00fchrt ihre Gesch\u00e4fte \u00fcber ihre weltweit verbundenen Unternehmen (zusammenfassend als \u201eSonova\u201c oder &#8220;Unternehmen&#8221; oder &#8220;wir&#8221; oder &#8220;unser&#8221; bezeichnet), die als unabh\u00e4ngige oder gemeinsame Datenverantwortliche in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/\" \/>\n<meta property=\"og:site_name\" content=\"Sonova International\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T17:55:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/globale-datenschutzrichtlinie\\\/\",\"url\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/globale-datenschutzrichtlinie\\\/\",\"name\":\"Globale Datenschutzrichtlinie - Sonova International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/#website\"},\"datePublished\":\"2022-03-28T11:01:47+00:00\",\"dateModified\":\"2026-06-02T17:55:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/globale-datenschutzrichtlinie\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sonova.com\\\/de\\\/globale-datenschutzrichtlinie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/globale-datenschutzrichtlinie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Datenschutzrichtlinie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/\",\"name\":\"Sonova International\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sonova.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Datenschutzrichtlinie - Sonova International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Datenschutzrichtlinie - Sonova International","og_description":"Globale Datenschutzrichtlinie \u00a0A. ALLGEMEINE INFORMATIONENDie Sonova AG ist nach schweizerischem Recht gegr\u00fcndet; sie hat ihren Sitz in der Laubisr\u00fctistrasse 28, 8712 St\u00e4fa, Schweiz. Die Sonova AG, die als Datenverantwortliche fungiert, f\u00fchrt ihre Gesch\u00e4fte \u00fcber ihre weltweit verbundenen Unternehmen (zusammenfassend als \u201eSonova\u201c oder &#8220;Unternehmen&#8221; oder &#8220;wir&#8221; oder &#8220;unser&#8221; bezeichnet), die als unabh\u00e4ngige oder gemeinsame Datenverantwortliche in [&hellip;]","og_url":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/","og_site_name":"Sonova International","article_modified_time":"2026-06-02T17:55:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/","url":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/","name":"Globale Datenschutzrichtlinie - Sonova International","isPartOf":{"@id":"https:\/\/www.sonova.com\/de\/#website"},"datePublished":"2022-03-28T11:01:47+00:00","dateModified":"2026-06-02T17:55:06+00:00","breadcrumb":{"@id":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sonova.com\/de\/globale-datenschutzrichtlinie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sonova.com\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Datenschutzrichtlinie"}]},{"@type":"WebSite","@id":"https:\/\/www.sonova.com\/de\/#website","url":"https:\/\/www.sonova.com\/de\/","name":"Sonova International","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sonova.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Sonova International","distributor_original_site_url":"https:\/\/www.sonova.com\/de\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/pages\/30974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/comments?post=30974"}],"version-history":[{"count":1,"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/pages\/30974\/revisions"}],"predecessor-version":[{"id":30975,"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/pages\/30974\/revisions\/30975"}],"wp:attachment":[{"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/media?parent=30974"}],"wp:term":[{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.sonova.com\/de\/wp-json\/wp\/v2\/news-type?post=30974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}